{"id":14578,"date":"2025-06-15T07:24:57","date_gmt":"2025-06-15T05:24:57","guid":{"rendered":"https:\/\/www.bretzel-liquide.com\/blog\/?p=14578"},"modified":"2025-06-15T07:24:57","modified_gmt":"2025-06-15T05:24:57","slug":"mon-pere-ce-heros","status":"publish","type":"post","link":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/","title":{"rendered":"mon p\u00e8re ce h\u00e9ros"},"content":{"rendered":"\n<figure class=\"wp-block-video\"><video height=\"720\" style=\"aspect-ratio: 1694 \/ 720;\" width=\"1694\" controls src=\"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2025\/06\/The-Untouchables-Brian-De-Palma-1987-Potemkine-fete-des-peres-mon-pere-ce-heros.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">mon p\u00e8re ce h\u00e9ros <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The Untouchables, Brian De Palma, 1987 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">tags : Potemkine, f\u00eate des p\u00e8res <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">alt : un enfant descendant un escalier dans son berceau, sauv\u00e9 par son p\u00e8re<\/p>\n","protected":false},"excerpt":{"rendered":"<p>mon p\u00e8re ce h\u00e9ros The Untouchables, Brian De Palma, 1987 tags : Potemkine, f\u00eate des p\u00e8res alt : un enfant descendant un escalier dans son berceau, sauv\u00e9 par son p\u00e8re<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[121],"tags":[2055,35,40,725,18],"class_list":["post-14578","post","type-post","status-publish","format-standard","hentry","category-les-belles-histoires-de-tonton-yves","tag-brian-de-palma","tag-cinema","tag-enfant","tag-fete-des-peres","tag-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>mon p\u00e8re ce h\u00e9ros - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur<\/title>\n<meta name=\"description\" content=\"mon p\u00e8re ce h\u00e9ros. un enfant descendant un escalier dans son berceau, sauv\u00e9 par son p\u00e8re\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"mon p\u00e8re ce h\u00e9ros - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur\" \/>\n<meta property=\"og:description\" content=\"mon p\u00e8re ce h\u00e9ros. un enfant descendant un escalier dans son berceau, sauv\u00e9 par son p\u00e8re\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-15T05:24:57+00:00\" \/>\n<meta name=\"author\" content=\"Yves Brette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yves Brette\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2025\\\/06\\\/15\\\/mon-pere-ce-heros\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2025\\\/06\\\/15\\\/mon-pere-ce-heros\\\/\"},\"author\":{\"name\":\"Yves Brette\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\"},\"headline\":\"mon p\u00e8re ce h\u00e9ros\",\"datePublished\":\"2025-06-15T05:24:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2025\\\/06\\\/15\\\/mon-pere-ce-heros\\\/\"},\"wordCount\":38,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\"},\"keywords\":[\"Brian De Palma\",\"cin\u00e9ma\",\"enfant\",\"f\u00eate des p\u00e8res\",\"video\"],\"articleSection\":[\"les belles histoires de tonton yves\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2025\\\/06\\\/15\\\/mon-pere-ce-heros\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2025\\\/06\\\/15\\\/mon-pere-ce-heros\\\/\",\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2025\\\/06\\\/15\\\/mon-pere-ce-heros\\\/\",\"name\":\"mon p\u00e8re ce h\u00e9ros - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#website\"},\"datePublished\":\"2025-06-15T05:24:57+00:00\",\"description\":\"mon p\u00e8re ce h\u00e9ros. un enfant descendant un escalier dans son berceau, sauv\u00e9 par son p\u00e8re\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2025\\\/06\\\/15\\\/mon-pere-ce-heros\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2025\\\/06\\\/15\\\/mon-pere-ce-heros\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2025\\\/06\\\/15\\\/mon-pere-ce-heros\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"mon p\u00e8re ce h\u00e9ros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/\",\"name\":\"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur\",\"description\":\"la face nord du bretzel liquide : humour absurde, images \u00e9tranges, microblogging\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\",\"name\":\"Yves Brette\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\",\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\",\"width\":150,\"height\":147,\"caption\":\"Yves Brette\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\"},\"sameAs\":[\"http:\\\/\\\/www.bretzel-liquide.com\\\/blog\"],\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/author\\\/yves\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"mon p\u00e8re ce h\u00e9ros - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur","description":"mon p\u00e8re ce h\u00e9ros. un enfant descendant un escalier dans son berceau, sauv\u00e9 par son p\u00e8re","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/","og_locale":"fr_FR","og_type":"article","og_title":"mon p\u00e8re ce h\u00e9ros - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur","og_description":"mon p\u00e8re ce h\u00e9ros. un enfant descendant un escalier dans son berceau, sauv\u00e9 par son p\u00e8re","og_url":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/","og_site_name":"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur","article_published_time":"2025-06-15T05:24:57+00:00","author":"Yves Brette","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Yves Brette"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/#article","isPartOf":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/"},"author":{"name":"Yves Brette","@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d"},"headline":"mon p\u00e8re ce h\u00e9ros","datePublished":"2025-06-15T05:24:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/"},"wordCount":38,"commentCount":0,"publisher":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d"},"keywords":["Brian De Palma","cin\u00e9ma","enfant","f\u00eate des p\u00e8res","video"],"articleSection":["les belles histoires de tonton yves"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/","url":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/","name":"mon p\u00e8re ce h\u00e9ros - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur","isPartOf":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#website"},"datePublished":"2025-06-15T05:24:57+00:00","description":"mon p\u00e8re ce h\u00e9ros. un enfant descendant un escalier dans son berceau, sauv\u00e9 par son p\u00e8re","breadcrumb":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bretzel-liquide.com\/blog\/2025\/06\/15\/mon-pere-ce-heros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bretzel-liquide.com\/blog\/"},{"@type":"ListItem","position":2,"name":"mon p\u00e8re ce h\u00e9ros"}]},{"@type":"WebSite","@id":"https:\/\/www.bretzel-liquide.com\/blog\/#website","url":"https:\/\/www.bretzel-liquide.com\/blog\/","name":"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur","description":"la face nord du bretzel liquide : humour absurde, images \u00e9tranges, microblogging","publisher":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bretzel-liquide.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d","name":"Yves Brette","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg","url":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg","contentUrl":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg","width":150,"height":147,"caption":"Yves Brette"},"logo":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg"},"sameAs":["http:\/\/www.bretzel-liquide.com\/blog"],"url":"https:\/\/www.bretzel-liquide.com\/blog\/author\/yves\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/posts\/14578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/comments?post=14578"}],"version-history":[{"count":1,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/posts\/14578\/revisions"}],"predecessor-version":[{"id":14580,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/posts\/14578\/revisions\/14580"}],"wp:attachment":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/media?parent=14578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/categories?post=14578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/tags?post=14578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}