{"id":19550,"date":"2026-04-12T09:11:00","date_gmt":"2026-04-12T07:11:00","guid":{"rendered":"https:\/\/www.bretzel-liquide.com\/blog\/?p=19550"},"modified":"2026-04-12T09:14:11","modified_gmt":"2026-04-12T07:14:11","slug":"j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran","status":"publish","type":"post","link":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/","title":{"rendered":"J.D. Vance quitte le Pakistan apr\u00e8s l&rsquo;\u00e9chec des n\u00e9gociations avec l&rsquo;Iran"},"content":{"rendered":"\n<figure class=\"wp-block-video\"><video height=\"640\" style=\"aspect-ratio: 640 \/ 640;\" width=\"640\" controls src=\"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2026\/04\/cheval-equitation-dressage-essaie-encore.mp4\"><\/video><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">J.D. Vance quitte le Pakistan apr\u00e8s l&rsquo;\u00e9chec des n\u00e9gociations avec l&rsquo;Iran <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">tag : essaie encore, si tu tombes de cheval remonte aussit\u00f4t\u00a0en selle, exercice pratique de diplomatie <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">alt : un cavalier s&rsquo;exer\u00e7ant au saut d&rsquo;obstacle se fait \u00e9jecter dans la rivi\u00e8re par sa monture qui refuse l&rsquo;obstacle<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Am\u00e9ricains, Iraniens et Pakistanais ont entam\u00e9 hier des n\u00e9gociations historiques pour trouver une issue au conflit. Les pourparlers se sont finis \u00e0 l&rsquo;aube aujourd&rsquo;hui et butent sur la question du programme nucl\u00e9aire iranien (<a href=\"https:\/\/www.leparisien.fr\/international\/iran\/direct-guerre-au-moyen-orient-jd-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran-12-04-2026-YYHLZRGQERHH3HV45A2KAONMKE.php\" type=\"link\" id=\"https:\/\/www.leparisien.fr\/international\/iran\/direct-guerre-au-moyen-orient-jd-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran-12-04-2026-YYHLZRGQERHH3HV45A2KAONMKE.php\" target=\"_blank\" rel=\"noreferrer noopener\">Le Parisien<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J.D. Vance quitte le Pakistan apr\u00e8s l&rsquo;\u00e9chec des n\u00e9gociations avec l&rsquo;Iran tag : essaie encore, si tu tombes de cheval remonte aussit\u00f4t\u00a0en selle, exercice pratique de diplomatie alt : un cavalier s&rsquo;exer\u00e7ant au saut d&rsquo;obstacle se fait \u00e9jecter dans la rivi\u00e8re par sa monture qui refuse l&rsquo;obstacle Am\u00e9ricains, Iraniens et Pakistanais ont entam\u00e9 hier des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[75,97],"tags":[181,367,112,2890,70,98,711,18],"class_list":["post-19550","post","type-post","status-publish","format-standard","hentry","category-attache-de-presse-puree","category-sportyves","tag-cheval","tag-guerre","tag-iran","tag-j-d-vance","tag-politique","tag-sport","tag-usa","tag-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>J.D. Vance quitte le Pakistan apr\u00e8s l&#039;\u00e9chec des n\u00e9gociations avec l&#039;Iran - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur<\/title>\n<meta name=\"description\" content=\"J.D. Vance quitte le Pakistan apr\u00e8s l&#039;\u00e9chec des n\u00e9gociations avec l&#039;Iran\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J.D. Vance quitte le Pakistan apr\u00e8s l&#039;\u00e9chec des n\u00e9gociations avec l&#039;Iran - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur\" \/>\n<meta property=\"og:description\" content=\"J.D. Vance quitte le Pakistan apr\u00e8s l&#039;\u00e9chec des n\u00e9gociations avec l&#039;Iran\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-12T07:11:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-12T07:14:11+00:00\" \/>\n<meta name=\"author\" content=\"Yves Brette\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yves Brette\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2026\\\/04\\\/12\\\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2026\\\/04\\\/12\\\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\\\/\"},\"author\":{\"name\":\"Yves Brette\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\"},\"headline\":\"J.D. Vance quitte le Pakistan apr\u00e8s l&rsquo;\u00e9chec des n\u00e9gociations avec l&rsquo;Iran\",\"datePublished\":\"2026-04-12T07:11:00+00:00\",\"dateModified\":\"2026-04-12T07:14:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2026\\\/04\\\/12\\\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\\\/\"},\"wordCount\":112,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\"},\"keywords\":[\"cheval\",\"guerre\",\"Iran\",\"J. D. Vance\",\"politique\",\"sport\",\"USA\",\"video\"],\"articleSection\":[\"attach\u00e9 de presse pur\u00e9e\",\"sportyves\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2026\\\/04\\\/12\\\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2026\\\/04\\\/12\\\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\\\/\",\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2026\\\/04\\\/12\\\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\\\/\",\"name\":\"J.D. Vance quitte le Pakistan apr\u00e8s l'\u00e9chec des n\u00e9gociations avec l'Iran - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#website\"},\"datePublished\":\"2026-04-12T07:11:00+00:00\",\"dateModified\":\"2026-04-12T07:14:11+00:00\",\"description\":\"J.D. Vance quitte le Pakistan apr\u00e8s l'\u00e9chec des n\u00e9gociations avec l'Iran\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2026\\\/04\\\/12\\\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2026\\\/04\\\/12\\\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/2026\\\/04\\\/12\\\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"J.D. Vance quitte le Pakistan apr\u00e8s l&rsquo;\u00e9chec des n\u00e9gociations avec l&rsquo;Iran\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/\",\"name\":\"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur\",\"description\":\"la face nord du bretzel liquide : humour absurde, images \u00e9tranges, microblogging\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\",\"name\":\"Yves Brette\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\",\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\",\"width\":150,\"height\":147,\"caption\":\"Yves Brette\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\"},\"sameAs\":[\"http:\\\/\\\/www.bretzel-liquide.com\\\/blog\"],\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/author\\\/yves\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J.D. Vance quitte le Pakistan apr\u00e8s l'\u00e9chec des n\u00e9gociations avec l'Iran - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur","description":"J.D. Vance quitte le Pakistan apr\u00e8s l'\u00e9chec des n\u00e9gociations avec l'Iran","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/","og_locale":"fr_FR","og_type":"article","og_title":"J.D. Vance quitte le Pakistan apr\u00e8s l'\u00e9chec des n\u00e9gociations avec l'Iran - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur","og_description":"J.D. Vance quitte le Pakistan apr\u00e8s l'\u00e9chec des n\u00e9gociations avec l'Iran","og_url":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/","og_site_name":"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur","article_published_time":"2026-04-12T07:11:00+00:00","article_modified_time":"2026-04-12T07:14:11+00:00","author":"Yves Brette","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Yves Brette"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/#article","isPartOf":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/"},"author":{"name":"Yves Brette","@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d"},"headline":"J.D. Vance quitte le Pakistan apr\u00e8s l&rsquo;\u00e9chec des n\u00e9gociations avec l&rsquo;Iran","datePublished":"2026-04-12T07:11:00+00:00","dateModified":"2026-04-12T07:14:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/"},"wordCount":112,"commentCount":0,"publisher":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d"},"keywords":["cheval","guerre","Iran","J. D. Vance","politique","sport","USA","video"],"articleSection":["attach\u00e9 de presse pur\u00e9e","sportyves"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/","url":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/","name":"J.D. Vance quitte le Pakistan apr\u00e8s l'\u00e9chec des n\u00e9gociations avec l'Iran - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur","isPartOf":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#website"},"datePublished":"2026-04-12T07:11:00+00:00","dateModified":"2026-04-12T07:14:11+00:00","description":"J.D. Vance quitte le Pakistan apr\u00e8s l'\u00e9chec des n\u00e9gociations avec l'Iran","breadcrumb":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bretzel-liquide.com\/blog\/2026\/04\/12\/j-d-vance-quitte-le-pakistan-apres-lechec-des-negociations-avec-liran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bretzel-liquide.com\/blog\/"},{"@type":"ListItem","position":2,"name":"J.D. Vance quitte le Pakistan apr\u00e8s l&rsquo;\u00e9chec des n\u00e9gociations avec l&rsquo;Iran"}]},{"@type":"WebSite","@id":"https:\/\/www.bretzel-liquide.com\/blog\/#website","url":"https:\/\/www.bretzel-liquide.com\/blog\/","name":"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur","description":"la face nord du bretzel liquide : humour absurde, images \u00e9tranges, microblogging","publisher":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bretzel-liquide.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d","name":"Yves Brette","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg","url":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg","contentUrl":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg","width":150,"height":147,"caption":"Yves Brette"},"logo":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg"},"sameAs":["http:\/\/www.bretzel-liquide.com\/blog"],"url":"https:\/\/www.bretzel-liquide.com\/blog\/author\/yves\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/posts\/19550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/comments?post=19550"}],"version-history":[{"count":2,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/posts\/19550\/revisions"}],"predecessor-version":[{"id":19554,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/posts\/19550\/revisions\/19554"}],"wp:attachment":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/media?parent=19550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/categories?post=19550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/tags?post=19550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}