{"id":1991,"count":2,"description":"","link":"https:\/\/www.bretzel-liquide.com\/blog\/tag\/agatha-christie\/","name":"Agatha Christie","slug":"agatha-christie","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Agatha Christie - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bretzel-liquide.com\/blog\/tag\/agatha-christie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Agatha Christie - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bretzel-liquide.com\/blog\/tag\/agatha-christie\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/tag\\\/agatha-christie\\\/\",\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/tag\\\/agatha-christie\\\/\",\"name\":\"Archives des Agatha Christie - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/tag\\\/agatha-christie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/tag\\\/agatha-christie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Agatha Christie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/\",\"name\":\"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur\",\"description\":\"la face nord du bretzel liquide : humour absurde, images \u00e9tranges, microblogging\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/#\\\/schema\\\/person\\\/16b498860410bff000499934f159633d\",\"name\":\"Yves Brette\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\",\"url\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\",\"contentUrl\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\",\"width\":150,\"height\":147,\"caption\":\"Yves Brette\"},\"logo\":{\"@id\":\"https:\\\/\\\/www.bretzel-liquide.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/headerchien.jpg\"},\"sameAs\":[\"http:\\\/\\\/www.bretzel-liquide.com\\\/blog\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Agatha Christie - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bretzel-liquide.com\/blog\/tag\/agatha-christie\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des Agatha Christie - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur","og_url":"https:\/\/www.bretzel-liquide.com\/blog\/tag\/agatha-christie\/","og_site_name":"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.bretzel-liquide.com\/blog\/tag\/agatha-christie\/","url":"https:\/\/www.bretzel-liquide.com\/blog\/tag\/agatha-christie\/","name":"Archives des Agatha Christie - \u00e0 l&#039;ombre d&#039;un paradoxe en fleur","isPartOf":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/tag\/agatha-christie\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.bretzel-liquide.com\/blog\/tag\/agatha-christie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bretzel-liquide.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Agatha Christie"}]},{"@type":"WebSite","@id":"https:\/\/www.bretzel-liquide.com\/blog\/#website","url":"https:\/\/www.bretzel-liquide.com\/blog\/","name":"\u00e0 l&#039;ombre d&#039;un paradoxe en fleur","description":"la face nord du bretzel liquide : humour absurde, images \u00e9tranges, microblogging","publisher":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bretzel-liquide.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/www.bretzel-liquide.com\/blog\/#\/schema\/person\/16b498860410bff000499934f159633d","name":"Yves Brette","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg","url":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg","contentUrl":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg","width":150,"height":147,"caption":"Yves Brette"},"logo":{"@id":"https:\/\/www.bretzel-liquide.com\/blog\/wp-content\/uploads\/2022\/01\/headerchien.jpg"},"sameAs":["http:\/\/www.bretzel-liquide.com\/blog"]}]}},"_links":{"self":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/tags\/1991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.bretzel-liquide.com\/blog\/wp-json\/wp\/v2\/posts?tags=1991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}